{"id":4703,"date":"2025-01-22T21:55:55","date_gmt":"2025-01-23T03:55:55","guid":{"rendered":"https:\/\/veracruzanosexcepcionahles.com\/?p=4703"},"modified":"2025-01-22T21:55:57","modified_gmt":"2025-01-23T03:55:57","slug":"inclusion-de-personas-con-discapacidad-fomenta-el-desarrollo-de-economias-mas-equitativas","status":"publish","type":"post","link":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/2025\/01\/22\/inclusion-de-personas-con-discapacidad-fomenta-el-desarrollo-de-economias-mas-equitativas\/","title":{"rendered":"Inclusi\u00f3n de personas con discapacidad fomenta el desarrollo de econom\u00edas m\u00e1s equitativas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&gt;Sensibilizan a servidores p\u00fablicos para impulsar un Veracruz m\u00e1s incluyente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Xalapa, Ver., mi\u00e9rcoles 22 de enero de 2025.-<\/strong> En el marco de una pol\u00edtica p\u00fablica inclusiva y equitativa, el Gobierno de Veracruz, a trav\u00e9s de la Secretar\u00eda de Trabajo, Previsi\u00f3n Social y Productividad (STPSP), en colaboraci\u00f3n con el Servicio Nacional de Empleo (SNE), garantiza el acceso a oportunidades laborales dignas para las personas con discapacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las principales iniciativas destacan la Red de Vinculaci\u00f3n Laboral, un programa que facilita la inserci\u00f3n laboral de personas con discapacidad y adultos mayores, conectando a buscadores de empleo con empresas comprometidas con la inclusi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las Ferias Nacionales de Empleo para la Inclusi\u00f3n Laboral, realizadas cada mes de octubre, son una plataforma para vincular directamente a personas en b\u00fasqueda de empleo con organizaciones inclusivas, promoviendo el acceso a trabajos adecuados a sus habilidades y competencias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuentan tambi\u00e9n con la estrategia Abriendo Espacios, dise\u00f1ada para atender a personas en situaci\u00f3n de vulnerabilidad, identificando sus necesidades espec\u00edficas y vincul\u00e1ndolas con oportunidades laborales acordes a sus capacidades. Un caso destacado en 2024 fue el taller dirigido a personas sordas, enfocado en empoderarlas y prepararlas para el mercado laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Valpar es una herramienta que eval\u00faa y certifica las habilidades y aptitudes de personas con discapacidad y adultos mayores, permitiendo un perfilamiento adecuado que mejora sus posibilidades de inserci\u00f3n laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de estas acciones, la dependencia organiz\u00f3 la charla Inclusi\u00f3n laboral para personas con discapacidad, impartida por Iv\u00e1n Osvaldo Montiel Taxilaga, reconocido por su compromiso en promover la inclusi\u00f3n, a fin de sensibilizar al personal y fortalecer el compromiso institucional con la igualdad de oportunidades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El secretario de Trabajo, Luis Arturo Santiago Mart\u00ednez, resalt\u00f3 el valor de la inclusi\u00f3n como un principio esencial del humanismo mexicano, aplicado por la gobernadora Roc\u00edo Nahle Garc\u00eda: \u201cLa inclusi\u00f3n no solo beneficia al individuo, sino que tambi\u00e9n fortalece nuestras comunidades y nuestro sentido de pertenencia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&gt;Sensibilizan a servidores p\u00fablicos para impulsar un Veracruz m\u00e1s incluyente. Xalapa, Ver., mi\u00e9rcoles 22 de enero de 2025.- En el marco de una pol\u00edtica p\u00fablica inclusiva y equitativa, el Gobierno de Veracruz, a trav\u00e9s de la Secretar\u00eda de Trabajo, Previsi\u00f3n Social y Productividad (STPSP), en colaboraci\u00f3n con el Servicio Nacional de Empleo (SNE), garantiza el&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[2],"tags":[],"class_list":["post-4703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobiernoestatal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/veracruzanosexcepcionahles.com\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-22-at-4.45.58-PM.jpeg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/pe8dhK-1dR","_links":{"self":[{"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/posts\/4703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/comments?post=4703"}],"version-history":[{"count":1,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/posts\/4703\/revisions"}],"predecessor-version":[{"id":4705,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/posts\/4703\/revisions\/4705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/media\/4704"}],"wp:attachment":[{"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/media?parent=4703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/categories?post=4703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veracruzanosexcepcionahles.com\/index.php\/wp-json\/wp\/v2\/tags?post=4703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}